{"id":1555,"date":"2023-06-02T01:57:32","date_gmt":"2023-06-02T01:57:32","guid":{"rendered":"http:\/\/worm-reducers.xyz\/china-best-sales-czpt-transmission-udl-0-18-series-worm-gearbox-worm-gearbox-back-drive\/"},"modified":"2023-06-02T01:57:32","modified_gmt":"2023-06-02T01:57:32","slug":"china-best-sales-czpt-transmission-udl-0-18-series-worm-gearbox-worm-gearbox-back-drive","status":"publish","type":"post","link":"https:\/\/worm-reducers.xyz\/th\/china-best-sales-czpt-transmission-udl-0-18-series-worm-gearbox-worm-gearbox-back-drive\/","title":{"rendered":"\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e2b\u0e19\u0e2d\u0e19 CZPT \u0e23\u0e38\u0e48\u0e19 UDL 0.18 \u0e08\u0e32\u0e01\u0e08\u0e35\u0e19 (\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e2d\u0e19)"},"content":{"rendered":"<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_0_tb_body  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p><h2>\u0e04\u0e33\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c<\/h2>\n<p>\n<p><p>Technical\u00a0Features<\/p>\n<p>\u00a0\u00a0The\u00a0high\u00a0degree\u00a0of\u00a0modularity\u00a0is\u00a0a\u00a0design\u00a0feature\u00a0of\u00a0SRC\u00a0helical\u00a0gearboxes\u00a0range.\u00a0It\u00a0can\u00a0be\u00a0connected\u00a0respectively\u00a0with\u00a0motors\u00a0such\u00a0as\u00a0normal\u00a0motor,\u00a0brake\u00a0motor,\u00a0explosion-proof\u00a0motor,\u00a0frequency\u00a0conversion\u00a0motor,\u00a0servo\u00a0motor,\u00a0IEC\u00a0motor\u00a0and\u00a0so\u00a0on.\u00a0This\u00a0kind\u00a0of\u00a0product\u00a0is\u00a0widely\u00a0used\u00a0in\u00a0drive\u00a0fields\u00a0such\u00a0as\u00a0textile,\u00a0foodstuff,\u00a0ceramics\u00a0packing,\u00a0logistics,\u00a0plastics\u00a0and\u00a0so\u00a0on.\u00a0It\u00a0is\u00a0possible\u00a0to\u00a0set\u00a0up\u00a0the\u00a0version\u00a0required\u00a0using\u00a0flanges\u00a0or\u00a0feet.<\/p>\n<p>\u00a0<\/p>\n<p>Products\u00a0characteristics\u00a0<\/p>\n<p>\u00a0\u00a0SRC\u00a0series\u00a0helical\u00a0gear\u00a0units\u00a0has\u00a0more\u00a0than\u00a04\u00a0types.\u00a0Power\u00a00.12-4kw;\u00a0Ratio\u00a03.66-54;\u00a0Torque\u00a0max\u00a0120-500Nm.\u00a0It\u00a0can\u00a0be\u00a0connected\u00a0(foot\u00a0or\u00a0flange)\u00a0discretionary\u00a0and\u00a0use\u00a0multi-mounting\u00a0positions\u00a0according\u00a0to\u00a0customers\u00a0requirements.<\/p>\n<p>Ground-hardened\u00a0helical\u00a0gears;<\/p>\n<p>Modularity,can\u00a0be\u00a0combined\u00a0in\u00a0many\u00a0forms;<\/p>\n<p>Aluminium\u00a0casing,\u00a0light\u00a0weight;<\/p>\n<p>Gears\u00a0in\u00a0carbonize\u00a0hard,\u00a0durable;<\/p>\n<p>Universal\u00a0mounting;<\/p>\n<p>Refined\u00a0design,space\u00a0effective\u00a0and\u00a0low\u00a0noise<\/p>\n<p>Structure feature<\/p>\n<p>Model\u00a0illuminate<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p>1<\/p>\n<\/td>\n<td>\n<p>Code\u00a0for\u00a0gear\u00a0units\u00a0series<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>2<\/p>\n<\/td>\n<td>\n<p>No\u00a0F\u00a0code\u00a0means\u00a0foot\u00a0mounted.With\u00a0F\u00a0code\u00a0B5\u00a0flange\u00a0mounted.With\u00a0Z\u00a0code\u00a0B14\u00a0flange\u00a0mounted<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>3<\/p>\n<\/td>\n<td>\n<p>Specification\u00a0code\u00a0of\u00a0gear\u00a0units\u00a001<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>4<\/p>\n<\/td>\n<td>\n<p>I,II,III,B5\u00a0Output\u00a0flange\u00a0specification,default\u00a0I\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok\u00a0\u00a0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>5<\/p>\n<\/td>\n<td>\n<p>IEC:\u00a0Input\u00a0flange\u00a0\u00a0HS:\u00a0shaft\u00a0input<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>6<\/p>\n<\/td>\n<td>\n<p>Transmission\u00a0ratio\u00a0of\u00a0gear\u00a0units<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>7<\/p>\n<\/td>\n<td>\n<p>M1:Mounting\u00a0position,\u00a0default\u00a0mounting\u00a0position\u00a0M1\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>8<\/p>\n<\/td>\n<td>\n<p>Position\u00a0diagram\u00a0for\u00a0motor\u00a0terminal\u00a0box,default\u00a0position\u00a0o\u00b0(R)\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>9<\/p>\n<\/td>\n<td>\n<p>No\u00a0mark\u00a0means\u00a0without\u00a0motor\u00a0\u00a0\u00a0Model\u00a0motor(poles\u00a0of\u00a0power)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>10<\/p>\n<\/td>\n<td>\n<p>Voltage\u00a0&#8211;\u00a0frequency<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>11<\/p>\n<\/td>\n<td>\n<p>Coil\u00a0in\u00a0position\u00a0for\u00a0motor,\u00a0default\u00a0position\u00a0S\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>4.2\u00a0Rotation\u00a0speed\u00a0n<\/p>\n<p>\u00a0<\/p>\n<p>n1\u00a0Gear\u00a0units\u00a0input\u00a0speed<\/p>\n<p>\u00a0<\/p>\n<p>n2\u00a0Gear\u00a0units\u00a0output\u00a0speed<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0If\u00a0driven\u00a0by\u00a0the\u00a0external\u00a0gearing,1400r\/min\u00a0or\u00a0lower\u00a0rotation\u00a0speed\u00a0is\u00a0suggested\u00a0so\u00a0as\u00a0to\u00a0optimize\u00a0the\u00a0working\u00a0conditions\u00a0and\u00a0prolong\u00a0the\u00a0service\u00a0life.Higher\u00a0input\u00a0rotation\u00a0speed\u00a0is\u00a0permitted,\u00a0but\u00a0in\u00a0this\u00a0situation,the\u00a0rated\u00a0torque\u00a0M2\u00a0will\u00a0be\u00a0reduced<br \/>\u00a0 \u00a0<\/p>\n<p>\u00a0<\/p>\n<p>4.5\u00a0Service\u00a0factor\u00a0fs<\/p>\n<p>\u00a0<\/p>\n<p>The\u00a0effect\u00a0of\u00a0the\u00a0driven\u00a0machine\u00a0on\u00a0the\u00a0gear\u00a0unit\u00a0is\u00a0taken\u00a0into\u00a0account\u00a0to\u00a0a\u00a0sufficient\u00a0level\u00a0of\u00a0accuracy\u00a0using\u00a0the\u00a0service\u00a0factor\u00a0fs.\u00a0The\u00a0service\u00a0factor\u00a0is\u00a0determined\u00a0according\u00a0to\u00a0the\u00a0daily\u00a0operation\u00a0time\u00a0and\u00a0the\u00a0starting\u00a0frequency\u00a0Z.\u00a0Three\u00a0load\u00a0classifications\u00a0are\u00a0considered\u00a0depending\u00a0on\u00a0the\u00a0mass\u00a0acceleration\u00a0factor.\u00a0You\u00a0can\u00a0read\u00a0off\u00a0the\u00a0service\u00a0factor\u00a0applicable\u00a0to\u00a0your\u00a0application\u00a0in\u00a0following\u00a0figure.\u00a0The\u00a0service\u00a0factor\u00a0selected\u00a0using\u00a0this\u00a0diagram\u00a0must\u00a0be\u00a0less\u00a0than\u00a0or\u00a0equal\u00a0to\u00a0the\u00a0service\u00a0factor\u00a0as\u00a0given\u00a0in\u00a0the\u00a0performance\u00a0parameter\u00a0table.<\/p>\n<p>\u00a0<\/p>\n<p>*\u00a0starting\u00a0frequency\u00a0Z:\u00a0The\u00a0cycles\u00a0include\u00a0all\u00a0starting\u00a0and\u00a0braking\u00a0procedures\u00a0as\u00a0well\u00a0as\u00a0change\u00a0overs\u00a0from\u00a0low\u00a0to\u00a0high\u00a0speed<\/p>\n<p>\u00a0<\/p>\n<p>SRC02..(HS) \u00a0Performance parameter<\/p>\n<p>\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p>kw<\/p>\n<\/td>\n<td>\n<p>Output\u00a0speed<\/p>\n<\/td>\n<td>\n<p>\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14<\/p>\n<\/td>\n<td>\n<p>Speed\u00a0ratio<\/p>\n<\/td>\n<td>\n<p>fs<\/p>\n<\/td>\n<td>\n<p>\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07<\/p>\n<\/td>\n<td>\n<p>IEC<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>0.37<\/p>\n<\/td>\n<td>\n<p>16.7rpm<\/p>\n<\/td>\n<td>\n<p>204N.M<\/p>\n<\/td>\n<td>\n<p>54<\/p>\n<\/td>\n<td>\n<p>1.0<\/p>\n<\/td>\n<td>\n<p>SRC02<\/p>\n<\/td>\n<td>\n<p>80B5\/B14<\/p>\n<p>\u00a0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p>\u00a0<\/p>\n<p>Helical gearbox outline dimension heet<\/p>\n<table>\n<tbody>\n<tr>\n<td>Foot\u00a0Code<\/td>\n<td>\u0e22\u0e39<\/td>\n<td>\u0e27\u0e35<\/td>\n<td>V1<\/td>\n<td>V2<\/td>\n<td>V3<\/td>\n<td>\u0e27<\/td>\n<td>X<\/td>\n<td>X1<\/td>\n<td>\u0e27\u0e32\u0e22<\/td>\n<td>\u0e0b<\/td>\n<\/tr>\n<tr>\n<td>B02<\/td>\n<td>18<\/td>\n<td>107.5<\/td>\n<td>60<\/td>\n<td>&#8211;<\/td>\n<td>130<\/td>\n<td>11<\/td>\n<td>136<\/td>\n<td>155<\/td>\n<td>100<\/td>\n<td>17<\/td>\n<\/tr>\n<tr>\n<td>M02<\/td>\n<td>25<\/td>\n<td>85<\/td>\n<td>&#8211;<\/td>\n<td>110<\/td>\n<td>120<\/td>\n<td>9<\/td>\n<td>112<\/td>\n<td>145<\/td>\n<td>80<\/td>\n<td>15<\/td>\n<\/tr>\n<tr>\n<td>M01<\/td>\n<td>18<\/td>\n<td>80<\/td>\n<td>&#8211;<\/td>\n<td>110<\/td>\n<td>120<\/td>\n<td>9<\/td>\n<td>118<\/td>\n<td>145<\/td>\n<td>80<\/td>\n<td>15<\/td>\n<\/tr>\n<tr>\n<td>B01<\/td>\n<td>18<\/td>\n<td>87<\/td>\n<td>50<\/td>\n<td>110<\/td>\n<td>&#8211;<\/td>\n<td>9<\/td>\n<td>118<\/td>\n<td>130<\/td>\n<td>90<\/td>\n<td>15<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>SRC helical gearbox with motor mounting position and terminal box orientation<\/p>\n<p>\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c<br \/>1 pc \/ carton,several cartons \/ wooden pallet  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\n                                \u0e04\u0e48\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07:<\/p>\n<div class=\"freight-tips help-tips J-help\">\n                                    <i class=\"ob-icon icon-problem\"><\/i><\/p>\n<div class=\"tips tips-system J-tips\">\n<div class=\"tips-con\">\n<p>\u0e04\u0e48\u0e32\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22<\/p>\n<p>                                            <span class=\"arrow arrow-top\"><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow arrow-in\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n                                        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/th>\n<td>\n                                \u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e08\u0e32\n                            <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19:<\/th>\n<td>Motor, Industry<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a:<\/th>\n<td>Cycloidal<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07:<\/th>\n<td>\u0e41\u0e02\u0e47\u0e07\u0e15\u0e31\u0e27<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 205\/Piece<\/strong><br \/>\n                                        <span title=\"1 \u0e0a\u0e34\u0e49\u0e19 (\u0e2a\u0e31\u0e48\u0e07\u0e02\u0e31\u0e49\u0e19\u0e15\u0e48\u0e33)\">1 \u0e0a\u0e34\u0e49\u0e19 (\u0e2a\u0e31\u0e48\u0e07\u0e02\u0e31\u0e49\u0e19\u0e15\u0e48\u0e33)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                                <i class=\"ob-icon icon-product\"><\/i>\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07<\/p><\/div>\n<div class=\"sample-order-desc\">UD2.2<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            \u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                        <i class=\"ob-icon icon-fill\"><\/i><\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_3.webp\" alt=\"\u0e22\u0e32\u0e25\u0e14\u0e1e\u0e22\u0e32\u0e18\u0e34\" width=\"800\" \/><\/p>\n<h2>\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23?<\/h2>\n<p>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e02\u0e32\u0e40\u0e02\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e43\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e13\u0e35 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e25\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e04\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e33\u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e15\u0e48\u0e33<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e2d\u0e19\u0e40\u0e1e\u0e25\u0e32\u0e01\u0e25\u0e27\u0e07<\/h2>\n<p>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32\u0e2d\u0e48\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e1a\u0e01\u0e31\u0e19 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e01\u0e47\u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e23\u0e31\u0e48\u0e27\u0e44\u0e2b\u0e25\u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e40\u0e1e\u0e25\u0e32\u0e01\u0e25\u0e27\u0e07\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e32\u0e07\u0e23\u0e38\u0e48\u0e19\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e01\u0e19\u0e04\u0e39\u0e48\u0e41\u0e25\u0e30\u0e41\u0e01\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e41\u0e19\u0e27\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e15\u0e31\u0e49\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e25\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e1a\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c 4 \u0e41\u0e25\u0e30 5 \u0e2a\u0e1b\u0e35\u0e14 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e32\u0e2a\u0e48\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<br \/>\u0e2d\u0e35\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e04\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e40\u0e2d\u0e32\u0e15\u0e4c\u0e1e\u0e38\u0e15\u0e17\u0e35\u0e48\u0e15\u0e48\u0e33\u0e21\u0e32\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e1a\u0e01\u0e27\u0e19\u0e15\u0e48\u0e33 \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e15\u0e48\u0e33 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e33\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Agknx Gearbox \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e44\u0e14\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e02\u0e22\u0e32\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e14\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e16\u0e39\u0e01\u0e01\u0e27\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32<br \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 Agknx<\/h2>\n<p>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 Agknx \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e1a\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1f\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1e\u0e23\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e14\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07 \u0e41\u0e15\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e22\u0e37\u0e49\u0e2d\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e39\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e1a\u0e1a\u0e08\u0e38\u0e14\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19<br \/>\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e35\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 Agknx \u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e39\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e25\u0e37\u0e48\u0e19\u0e44\u0e16\u0e25\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e17\u0e18\u0e4c\u0e2a\u0e39\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e21\u0e38\u0e21\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e04\u0e48\u0e32\u0e2a\u0e31\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e41\u0e23\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e17\u0e32\u0e19 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 Agknx \u0e22\u0e31\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e44\u0e19\u0e0b\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2b\u0e25\u0e48\u0e2d\u0e1f\u0e2d\u0e2a\u0e1f\u0e2d\u0e23\u0e31\u0e2a\u0e1a\u0e23\u0e2d\u0e19\u0e0b\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e07\u0e35\u0e22\u0e1a \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e31\u0e19\u0e1c\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e15\u0e48\u0e33<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 Agknx \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e1a\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e15\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e20\u0e32\u0e23\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2d\u0e31\u0e19\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e02\u0e2d\u0e07 Sumitomo Heavy Industries \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a \u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e25\u0e32\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e02\u0e2d\u0e07 Agknx \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e02\u0e2d\u0e07 Agknx \u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e25\u0e14\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e1a\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e41\u0e23\u0e07\u0e01\u0e14\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_3.webp\" alt=\"\u0e22\u0e32\u0e25\u0e14\u0e1e\u0e22\u0e32\u0e18\u0e34\" width=\"800\" \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e04\u0e2d<\/h2>\n<p>\u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e04\u0e2d \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e41\u0e23\u0e01 \u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e27\u0e07\u0e01\u0e25\u0e21\u0e42\u0e04\u0e19\u0e1f\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e27\u0e07\u0e01\u0e25\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e27\u0e48\u0e32 \u0e42\u0e14\u0e22\u0e1b\u0e01\u0e15\u0e34\u0e41\u0e25\u0e49\u0e27\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e19\u0e35\u0e49\u0e17\u0e33\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1f\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e34\u0e14\u0e01\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e08\u0e43\u0e0a\u0e49\u0e42\u0e21\u0e14\u0e39\u0e25\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e42\u0e15\u0e49\u0e15\u0e2d\u0e1a\u0e42\u0e21\u0e14\u0e39\u0e25\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e41\u0e01\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e04\u0e27\u0e23\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e27\u0e07\u0e01\u0e25\u0e21\u0e14\u0e49\u0e27\u0e22<br \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e04\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e01\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e17\u0e19\u0e17\u0e32\u0e19\u0e2a\u0e39\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2b\u0e19\u0e32\u0e01\u0e27\u0e48\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1f\u0e37\u0e2d\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14\u0e01\u0e27\u0e48\u0e32\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e44\u0e14\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e01\u0e23\u0e39\u0e19\u0e33\u0e41\u0e1a\u0e1a\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<br \/>\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e04\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e08\u0e30\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e38\u0e1a\u0e41\u0e02\u0e47\u0e07 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e08\u0e30\u0e17\u0e33\u0e08\u0e32\u0e01\u0e17\u0e2d\u0e07\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2b\u0e25\u0e48\u0e2d \u0e43\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e13\u0e35 \u0e2d\u0e32\u0e08\u0e43\u0e0a\u0e49\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2b\u0e25\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e17\u0e2d\u0e07\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e1c\u0e2a\u0e21\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49<br \/>\u0e01\u0e32\u0e23\u0e42\u0e01\u0e48\u0e07\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e32\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e1e\u0e32\u0e23\u0e32\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07 \u0e21\u0e38\u0e21\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07 \u0e25\u0e49\u0e27\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e01\u0e48\u0e07\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e32\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e1e\u0e32\u0e23\u0e32\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e01\u0e48\u0e07\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e32\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<br \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e04\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e14\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e39\u0e07 \u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e27\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e44\u0e14\u0e49 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e19\u0e40\u0e1e\u0e25\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25\u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a<br \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07<\/h2>\n<p>\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e41\u0e01\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e40\u0e2a\u0e49\u0e19\u0e23\u0e2d\u0e1a\u0e27\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e27\u0e48\u0e32 \u0e41\u0e1a\u0e1a\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e08\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1f\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e2d\u0e1a \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e04\u0e39\u0e48\u0e08\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e2a\u0e2d\u0e07\u0e1f\u0e31\u0e19 \u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e1a\u0e19\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e0b\u0e49\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e27\u0e32 \u0e23\u0e30\u0e22\u0e30\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e04\u0e37\u0e2d\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e08\u0e38\u0e14\u0e1a\u0e19\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e23\u0e2d\u0e1a \u0e21\u0e38\u0e21\u0e19\u0e33\u0e04\u0e37\u0e2d\u0e21\u0e38\u0e21\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e2b\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1f\u0e31\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e41\u0e01\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e04\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2b\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e02\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e48\u0e2d\u0e07\u0e25\u0e34\u0e48\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e08\u0e32\u0e30\u0e23\u0e39\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e1a\u0e19\u0e40\u0e1e\u0e25\u0e32\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e2a\u0e01\u0e23\u0e39\u0e22\u0e36\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e36\u0e14\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e14\u0e38\u0e21<br \/>\u0e16\u0e31\u0e07\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e23\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e17\u0e32\u0e19\u0e15\u0e48\u0e33 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e22\u0e34\u0e48\u0e07\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e22\u0e31\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e02\u0e27\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e19\u0e27\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e41\u0e1c\u0e48\u0e19\u0e01\u0e31\u0e49\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e31\u0e48\u0e27\u0e44\u0e2b\u0e25<br \/>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e2d\u0e19 I260 \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e32\u0e2a\u0e48\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e1b\u0e37\u0e19\u0e41\u0e1a\u0e1a\u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07\u0e40\u0e23\u0e35\u0e22\u0e27 \u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e19\u0e35\u0e49\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e15\u0e48\u0e33\u0e16\u0e36\u0e07\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e15\u0e48\u0e33 \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14\u0e2a\u0e39\u0e07 \u0e43\u0e19\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e02\u0e19\u0e32\u0e14\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e17\u0e19\u0e15\u0e48\u0e2d\u0e41\u0e23\u0e07\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01\u0e44\u0e14\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_3.webp\" alt=\"\u0e22\u0e32\u0e25\u0e14\u0e1e\u0e22\u0e32\u0e18\u0e34\" width=\"800\" \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07<\/h2>\n<p>\u0e0a\u0e38\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e23\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e43\u0e19\u0e02\u0e19\u0e32\u0e14\u0e01\u0e30\u0e17\u0e31\u0e14\u0e23\u0e31\u0e14 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14\u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e25\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e21\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e35\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e33\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e17\u0e33\u0e1b\u0e0f\u0e34\u0e01\u0e34\u0e23\u0e34\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e2b\u0e30<br \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e16\u0e39\u0e01\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e14\u0e2a\u0e39\u0e07 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e32\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e23\u0e07 \u0e41\u0e15\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e25\u0e32\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e02\u0e19\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e22\u0e31\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e15\u0e48\u0e33\u0e41\u0e15\u0e48\u0e41\u0e23\u0e07\u0e1a\u0e34\u0e14\u0e2a\u0e39\u0e07\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<br \/>\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e41\u0e23\u0e01 \u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e08\u0e30\u0e2b\u0e21\u0e38\u0e19\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e25\u0e44\u0e01\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e21\u0e38\u0e21\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e22\u0e31\u0e07\u0e25\u0e47\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49 \u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19\u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e25\u0e44\u0e01\u0e19\u0e35\u0e49\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e44\u0e14\u0e49\u0e43\u0e19\u0e25\u0e34\u0e1f\u0e15\u0e4c \u0e23\u0e2d\u0e01\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e42\u0e0b\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e31\u0e22\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c<br \/>\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e2d\u0e35\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19\u0e04\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e21\u0e35\u0e41\u0e01\u0e19\u0e2a\u0e2d\u0e07\u0e41\u0e01\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e09\u0e32\u0e01\u0e01\u0e31\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e2a\u0e2d\u0e07\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 \u0e40\u0e2a\u0e49\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e23\u0e48\u0e27\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e41\u0e01\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e15\u0e31\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e1e\u0e34\u0e17\u0e0a\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e01\u0e19\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e2b\u0e19\u0e2d\u0e19 CZPT \u0e23\u0e38\u0e48\u0e19 UDL 0.18 \u0e08\u0e32\u0e01\u0e08\u0e35\u0e19 (\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e2d\u0e19)\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e2b\u0e19\u0e2d\u0e19 CZPT \u0e23\u0e38\u0e48\u0e19 UDL 0.18 \u0e08\u0e32\u0e01\u0e08\u0e35\u0e19 (\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e14\u0e23\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e2d\u0e19)\"><br \/>editor by CX 2023-06-02<\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description Technical\u00a0Features \u00a0\u00a0The\u00a0high\u00a0degree\u00a0of\u00a0modularity\u00a0is\u00a0a\u00a0design\u00a0feature\u00a0of\u00a0SRC\u00a0helical\u00a0gearboxes\u00a0range.\u00a0It\u00a0can\u00a0be\u00a0connected\u00a0respectively\u00a0with\u00a0motors\u00a0such\u00a0as\u00a0normal\u00a0motor,\u00a0brake\u00a0motor,\u00a0explosion-proof\u00a0motor,\u00a0frequency\u00a0conversion\u00a0motor,\u00a0servo\u00a0motor,\u00a0IEC\u00a0motor\u00a0and\u00a0so\u00a0on.\u00a0This\u00a0kind\u00a0of\u00a0product\u00a0is\u00a0widely\u00a0used\u00a0in\u00a0drive\u00a0fields\u00a0such\u00a0as\u00a0textile,\u00a0foodstuff,\u00a0ceramics\u00a0packing,\u00a0logistics,\u00a0plastics\u00a0and\u00a0so\u00a0on.\u00a0It\u00a0is\u00a0possible\u00a0to\u00a0set\u00a0up\u00a0the\u00a0version\u00a0required\u00a0using\u00a0flanges\u00a0or\u00a0feet. \u00a0 Products\u00a0characteristics\u00a0 \u00a0\u00a0SRC\u00a0series\u00a0helical\u00a0gear\u00a0units\u00a0has\u00a0more\u00a0than\u00a04\u00a0types.\u00a0Power\u00a00.12-4kw;\u00a0Ratio\u00a03.66-54;\u00a0Torque\u00a0max\u00a0120-500Nm.\u00a0It\u00a0can\u00a0be\u00a0connected\u00a0(foot\u00a0or\u00a0flange)\u00a0discretionary\u00a0and\u00a0use\u00a0multi-mounting\u00a0positions\u00a0according\u00a0to\u00a0customers\u00a0requirements. Ground-hardened\u00a0helical\u00a0gears; Modularity,can\u00a0be\u00a0combined\u00a0in\u00a0many\u00a0forms; Aluminium\u00a0casing,\u00a0light\u00a0weight; Gears\u00a0in\u00a0carbonize\u00a0hard,\u00a0durable; Universal\u00a0mounting; Refined\u00a0design,space\u00a0effective\u00a0and\u00a0low\u00a0noise Structure feature Model\u00a0illuminate 1 Code\u00a0for\u00a0gear\u00a0units\u00a0series 2 No\u00a0F\u00a0code\u00a0means\u00a0foot\u00a0mounted.With\u00a0F\u00a0code\u00a0B5\u00a0flange\u00a0mounted.With\u00a0Z\u00a0code\u00a0B14\u00a0flange\u00a0mounted 3 Specification\u00a0code\u00a0of\u00a0gear\u00a0units\u00a001 4 I,II,III,B5\u00a0Output\u00a0flange\u00a0specification,default\u00a0I\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok\u00a0\u00a0 5 IEC:\u00a0Input\u00a0flange\u00a0\u00a0HS:\u00a0shaft\u00a0input 6 Transmission\u00a0ratio\u00a0of\u00a0gear\u00a0units 7 M1:Mounting\u00a0position,\u00a0default\u00a0mounting\u00a0position\u00a0M1\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok 8 Position\u00a0diagram\u00a0for\u00a0motor\u00a0terminal\u00a0box,default\u00a0position\u00a0o\u00b0(R)\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok 9 No\u00a0mark\u00a0means\u00a0without\u00a0motor\u00a0\u00a0\u00a0Model\u00a0motor(poles\u00a0of\u00a0power) 10 Voltage\u00a0&#8211;\u00a0frequency 11 Coil\u00a0in\u00a0position\u00a0for\u00a0motor,\u00a0default\u00a0position\u00a0S\u00a0not\u00a0to\u00a0write\u00a0out\u00a0is\u00a0ok \u00a0 \u00a0 4.2\u00a0Rotation\u00a0speed\u00a0n \u00a0 n1\u00a0Gear\u00a0units\u00a0input\u00a0speed \u00a0 n2\u00a0Gear\u00a0units\u00a0output\u00a0speed \u00a0 \u00a0\u00a0If\u00a0driven\u00a0by\u00a0the\u00a0external\u00a0gearing,1400r\/min\u00a0or\u00a0lower\u00a0rotation\u00a0speed\u00a0is\u00a0suggested\u00a0so\u00a0as\u00a0to\u00a0optimize\u00a0the\u00a0working\u00a0conditions\u00a0and\u00a0prolong\u00a0the\u00a0service\u00a0life.Higher\u00a0input\u00a0rotation\u00a0speed\u00a0is\u00a0permitted,\u00a0but\u00a0in\u00a0this\u00a0situation,the\u00a0rated\u00a0torque\u00a0M2\u00a0will\u00a0be\u00a0reduced\u00a0 \u00a0 \u00a0 4.5\u00a0Service\u00a0factor\u00a0fs \u00a0 The\u00a0effect\u00a0of\u00a0the\u00a0driven\u00a0machine\u00a0on\u00a0the\u00a0gear\u00a0unit\u00a0is\u00a0taken\u00a0into\u00a0account\u00a0to\u00a0a\u00a0sufficient\u00a0level\u00a0of\u00a0accuracy\u00a0using\u00a0the\u00a0service\u00a0factor\u00a0fs.\u00a0The\u00a0service\u00a0factor\u00a0is\u00a0determined\u00a0according\u00a0to\u00a0the\u00a0daily\u00a0operation\u00a0time\u00a0and\u00a0the\u00a0starting\u00a0frequency\u00a0Z.\u00a0Three\u00a0load\u00a0classifications\u00a0are\u00a0considered\u00a0depending\u00a0on\u00a0the\u00a0mass\u00a0acceleration\u00a0factor.\u00a0You\u00a0can\u00a0read\u00a0off\u00a0the\u00a0service\u00a0factor\u00a0applicable\u00a0to\u00a0your\u00a0application\u00a0in\u00a0following\u00a0figure.\u00a0The\u00a0service\u00a0factor\u00a0selected\u00a0using\u00a0this\u00a0diagram\u00a0must\u00a0be\u00a0less\u00a0than\u00a0or\u00a0equal\u00a0to\u00a0the\u00a0service\u00a0factor\u00a0as\u00a0given\u00a0in\u00a0the\u00a0performance\u00a0parameter\u00a0table. \u00a0 *\u00a0starting\u00a0frequency\u00a0Z:\u00a0The\u00a0cycles\u00a0include\u00a0all\u00a0starting\u00a0and\u00a0braking\u00a0procedures\u00a0as\u00a0well\u00a0as\u00a0change\u00a0overs\u00a0from\u00a0low\u00a0to\u00a0high\u00a0speed \u00a0 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[12,20,21,538,384,542,389,390,363],"class_list":["post-1555","post","type-post","status-publish","format-standard","hentry","category-worm-reducers","tag-china-gearbox","tag-gearbox","tag-gearbox-china","tag-gearbox-transmission","tag-gearbox-worm-drive","tag-transmission-gearbox","tag-worm-drive","tag-worm-drive-gearbox","tag-worm-gearbox"],"_links":{"self":[{"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/posts\/1555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/comments?post=1555"}],"version-history":[{"count":0,"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/posts\/1555\/revisions"}],"wp:attachment":[{"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/media?parent=1555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/categories?post=1555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worm-reducers.xyz\/th\/wp-json\/wp\/v2\/tags?post=1555"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}