{"id":1505,"date":"2023-03-27T08:01:27","date_gmt":"2023-03-27T08:01:27","guid":{"rendered":"http:\/\/worm-reducers.xyz\/china-factory-direct-sales-of-aluminum-shell-small-mrv50-rv-worm-gear-worm-reducer-gear-box-worm-gearbox-china\/"},"modified":"2023-03-27T08:01:27","modified_gmt":"2023-03-27T08:01:27","slug":"china-factory-direct-sales-of-aluminum-shell-small-mrv50-rv-worm-gear-worm-reducer-gear-box-worm-gearbox-china","status":"publish","type":"post","link":"https:\/\/worm-reducers.xyz\/fr\/china-factory-direct-sales-of-aluminum-shell-small-mrv50-rv-worm-gear-worm-reducer-gear-box-worm-gearbox-china\/","title":{"rendered":"Vente directe d'usine en Chine de r\u00e9ducteurs \u00e0 vis sans fin Mrv50 pour camping-cars, bo\u00eetier en aluminium, petits mod\u00e8les."},"content":{"rendered":"<p><h2>Description du produit<\/h2>\n<p>\n<p><h3><b>\u00c0 propos de nous\u00a0<\/b><\/h3>\n<p>one.We manufacture and market HB,XB,P, F, S,K,R series speed retarders and transmissions. 2.A range of versions are offered. <b>You are welcome to inquire.<\/b><\/p>\n<p>3.We supply certifications:CO\/PVOC\/ FERI\/SUNCAP\/ISO 9001:2008<\/p>\n<p><p>four.OEM service :logo,lable ,guide ,and packages<\/p>\n<p>Description du produit<\/p>\n<p><p>\u00a0<\/p>\n<p><p>FC Parallel Shaft Helical Gearmotor<\/p>\n<p>\n<p><p>one. FC collection parallel shaft helical gearmotor is primarily based on the style of parallel shaft structure , which have a centre length in between input and output shaft.<br \/>2. Compact design, regular running, higher transmission efficiency, sturdy carrying capability.<br \/>three. The materials of gears is 20CrMnTi alloy steel and the hardness can get to to HRC58\u00b0~ 62\u00b0 following tempering, cementiting, quenching and many others. heat treatment. All the gears are processed by correct grinding and the precision can achieve to quality 6~5.<br \/>four. The goods have been largely utilized in cranes, conveyors, ceramic machinery, and so on.<br \/>Type and specification: FC37~FC157<\/p>\n<p>Param\u00e8tres de l'article<\/p>\n<p>\n<p>\n<p>Profil de l'organisation<\/p>\n<p><p>\u00a0<\/p>\n<p>FAQ<\/p>\n<p><p>\u00a0<\/p>\n<p><b>1. How to decide on a gearbox which meets our need?<\/b><br \/>You can refer to our catalogue to choose the gearbox or we can support to choose when you supply<br \/>the technological information of required output torque, output speed and motor parameter and so on.<\/p>\n<p><b>two. What details shall we give prior to putting a acquire buy?<\/b><br \/>a) Kind of the gearbox, ratio, input and output kind, enter flange, mounting position, and motor informationetc.<br \/>b) Housing coloration.<br \/>c) Buy amount.<br \/>d) Other specific specifications.<\/p>\n<p><b>three. What industries are your gearboxes getting employed?<\/b><br \/>Our gearboxes are widely employed in the regions of textile, meals processing, beverage, chemical market,<br \/>escalator,automated storage tools, metallurgy, tabacco, environmental security, logistics and and so forth.<\/p>\n<p><b>four. Do you promote motors?<\/b><br \/>We have stable motor suppliers who have been coperating with us for a extended-time. They can offer motors<br \/>with higher quality.<br \/>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Application:<\/th>\n<td>Machinery, Car, Lifting Equipment<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Duret\u00e9:<\/th>\n<td>Surface dentaire durcie<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installation:<\/th>\n<td>Type horizontal<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Mise en page:<\/th>\n<td>Expansion<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Forme de l'engrenage :<\/th>\n<td>Engrenage cylindrique<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u00c9tape:<\/th>\n<td>quatre \u00e9tapes<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Exemples :<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 2000\/Piece<\/strong><br \/>\n                                        <span title=\"1 pi\u00e8ce (commande minimale)\">1 pi\u00e8ce (commande minimale)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Demande d'\u00e9chantillon<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i><br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Application:<\/th>\n<td>Machinery, Car, Lifting Equipment<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Duret\u00e9:<\/th>\n<td>Surface dentaire durcie<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installation:<\/th>\n<td>Type horizontal<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Mise en page:<\/th>\n<td>Expansion<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Forme de l'engrenage :<\/th>\n<td>Engrenage cylindrique<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">\u00c9tape:<\/th>\n<td>quatre \u00e9tapes<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Exemples :<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 2000\/Piece<\/strong><br \/>\n                                        <span title=\"1 pi\u00e8ce (commande minimale)\">1 pi\u00e8ce (commande minimale)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Demande d'\u00e9chantillon<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i><br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Qu'est-ce qu'un r\u00e9ducteur \u00e0 vis sans fin ?<\/h2>\n<p>Le r\u00e9ducteur \u00e0 vis sans fin sert \u00e0 modifier la vitesse de sortie d'un appareil m\u00e9canique. Il se compose d'une vis sans fin et d'engrenages h\u00e9lico\u00efdaux mont\u00e9s en entr\u00e9e de l'\u00e9quipement. Dans certains cas, ce syst\u00e8me de r\u00e9duction peut \u00eatre multi-\u00e9tages, permettant d'atteindre des vitesses de sortie extr\u00eamement faibles. Il pr\u00e9sente l'avantage d'une faible consommation d'\u00e9nergie et de faibles vibrations.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_3.webp\" alt=\"r\u00e9ducteur de vers\" width=\"800\" \/>r\u00e9ducteur \u00e0 vis sans fin \u00e0 arbre creux<\/h2>\n<p>Le r\u00e9ducteur \u00e0 vis sans fin est un dispositif efficace pour r\u00e9duire la vitesse des \u00e9quipements m\u00e9caniques. L'utilisation d'acier dur ou de m\u00e9taux non ferreux pour la vis sans fin accro\u00eet son rendement. Les vis sans fin en acier dur g\u00e9n\u00e8rent davantage de chaleur que celles en acier doux. La diff\u00e9rence de dilatation thermique engendre des jeux entre les surfaces d'engr\u00e8nement. Malgr\u00e9 ses nombreux avantages, le r\u00e9ducteur \u00e0 vis sans fin est sujet aux fuites d'huile, ce qui peut poser probl\u00e8me pour diverses raisons.<br \/>Les r\u00e9ducteurs \u00e0 vis sans fin \u00e0 arbre creux sont disponibles avec diff\u00e9rents rapports de r\u00e9duction et sont compatibles avec de nombreux types de moteurs. Certains existent en versions \u00e0 un ou deux axes et peuvent \u00eatre mont\u00e9s horizontalement ou verticalement. Ils sont \u00e9galement disponibles avec des rapports interm\u00e9diaires, ainsi qu'en versions \u00e0 quatre ou cinq vitesses. Des arbres de sortie suppl\u00e9mentaires peuvent y \u00eatre raccord\u00e9s.<br \/>Un autre type de r\u00e9ducteur \u00e0 vis sans fin est le r\u00e9ducteur multi-\u00e9tages. Ce r\u00e9ducteur poss\u00e8de plusieurs \u00e9tages, ce qui lui permet de r\u00e9duire la vitesse \u00e0 des r\u00e9gimes de sortie extr\u00eamement bas. Outre son rapport de transmission \u00e9lev\u00e9, le r\u00e9ducteur multi-\u00e9tages se caract\u00e9rise par un faible niveau sonore, de faibles vibrations et une faible consommation d'\u00e9nergie.<br \/>Les r\u00e9ducteurs \u00e0 vis sans fin offrent des solutions compactes et un couple accru. Agknx Gearbox propose des r\u00e9ducteurs \u00e0 vis sans fin qui r\u00e9solvent les probl\u00e8mes de r\u00e9duction de vitesse courants. L'entreprise a \u00e9galement \u00e9tendu sa gamme de produits au march\u00e9 des salles de bains. Compar\u00e9 \u00e0 un r\u00e9ducteur standard, le r\u00e9ducteur \u00e0 vis sans fin se caract\u00e9rise par un prix plus bas et un couple de sortie sup\u00e9rieur.<br \/>Engrenage \u00e0 vis sans fin Agknx<\/h2>\n<p>Le r\u00e9ducteur \u00e0 vis sans fin de type Agknx, \u00e0 contact lin\u00e9aire multident\u00e9, est largement utilis\u00e9 dans les machines lourdes. Ces engrenages se caract\u00e9risent par une capacit\u00e9 de charge \u00e9lev\u00e9e, mais sont tr\u00e8s sensibles aux d\u00e9fauts d'alignement et de fabrication. En revanche, le contact ponctuel permet d'am\u00e9liorer leur fiabilit\u00e9 et d'accro\u00eetre leur capacit\u00e9 \u00e0 supporter des charges plus importantes.<br \/>Un autre avantage majeur de la roue dent\u00e9e \u00e0 vis sans fin Agknx r\u00e9side dans sa capacit\u00e9 de charge \u00e9lev\u00e9e. La conception du profil des dents assure un glissement relatif important, ce qui am\u00e9liore le rendement et la capacit\u00e9 de charge. De plus, l'angle important entre la direction de glissement et la ligne de contact garantit un faible coefficient de frottement. La roue dent\u00e9e \u00e0 vis sans fin Agknx est \u00e9galement fabriqu\u00e9e en acier c\u00e9ment\u00e9 et en bronze phosphoreux de haute qualit\u00e9, lui conf\u00e9rant une durabilit\u00e9 exceptionnelle. Enfin, la grande pr\u00e9cision du profil des dents assure un fonctionnement silencieux et une faible variation de vitesse.<br \/>Les r\u00e9ducteurs \u00e0 vis sans fin Agknx sont con\u00e7us pour fonctionner jusqu'\u00e0 dix heures par jour sous charge constante. Leur conception repose sur la vaste exp\u00e9rience de Sumitomo Heavy Industries dans le domaine des r\u00e9ducteurs. La texture lisse des surfaces et le profil pr\u00e9cis des dents des engrenages garantissent leur r\u00e9sistance aux charges \u00e9lev\u00e9es sans endommager le film lubrifiant. De plus, les arbres \u00e0 vis sans fin Agknx sont sp\u00e9cialement con\u00e7us pour offrir la rigidit\u00e9 optimale.<br \/>Les r\u00e9ducteurs \u00e0 vis sans fin Agknx sont con\u00e7us pour optimiser la capacit\u00e9 de charge tout en minimisant la consommation d'\u00e9nergie. Leur denture enti\u00e8rement engren\u00e9e r\u00e9duit la pression exerc\u00e9e sur les dents de la vis sans fin et augmente la capacit\u00e9 de charge.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_3.webp\" alt=\"r\u00e9ducteur de vers\" width=\"800\" \/>engrenage \u00e0 vis sans fin \u00e0 double gorge<\/h2>\n<p>Plusieurs \u00e9l\u00e9ments sont \u00e0 prendre en compte lors du choix d'une vis sans fin \u00e0 double gorge. Premi\u00e8rement, le diam\u00e8tre du cercle de pied doit correspondre au diam\u00e8tre primitif de la roue dent\u00e9e principale. Cette mesure s'effectue g\u00e9n\u00e9ralement en mesurant la distance entre deux dents adjacentes. On peut \u00e9galement utiliser le module normal de la vis sans fin, c'est-\u00e0-dire la valeur saisie dans la bo\u00eete de dialogue du module. De plus, le pas axial de la vis sans fin doit \u00eatre \u00e9gal au diam\u00e8tre primitif de la roue dent\u00e9e principale.<br \/>Les engrenages \u00e0 vis sans fin \u00e0 double gorge sont un excellent choix pour les applications exigeantes. Leur conception est id\u00e9ale pour les applications intensives car elle assure une liaison plus \u00e9troite entre la vis sans fin et la roue dent\u00e9e. Plus compacts que d'autres types d'engrenages, ils sont comparables \u00e0 une vis-m\u00e8re \u00e0 pas fin.<br \/>Le rendement d'un engrenage \u00e0 vis sans fin \u00e0 double gorge d\u00e9pend des mat\u00e9riaux utilis\u00e9s pour la roue dent\u00e9e et la vis sans fin. G\u00e9n\u00e9ralement, les roues dent\u00e9es sont en acier c\u00e9ment\u00e9, tandis que les engrenages \u00e0 vis sans fin sont en bronze ou en fonte. Dans certains cas, on peut utiliser une combinaison de fonte et de bronze.<br \/>La d\u00e9formation de l'arbre de la vis sans fin est \u00e9galement influenc\u00e9e par les param\u00e8tres de la denture. La hauteur des dents, l'angle de pression et les dimensions ont tous une incidence sur cette d\u00e9formation. De plus, le nombre de filets de la vis sans fin constitue un autre param\u00e8tre important.<br \/>Les engrenages \u00e0 vis sans fin \u00e0 double gorge sont couramment utilis\u00e9s dans les applications industrielles n\u00e9cessitant une r\u00e9duction de vitesse importante. La vis sans fin poss\u00e8de une denture concave et interne ajustable permettant d'obtenir diff\u00e9rents rapports de r\u00e9duction. Les engrenages et ensembles vis sans fin doivent \u00eatre correctement mont\u00e9s sur leurs arbres afin d'\u00e9viter tout retour de force.<br \/>engrenage \u00e0 vis sans fin en laiton<\/h2>\n<p>Le principe de fonctionnement de base d'un r\u00e9ducteur \u00e0 vis sans fin en laiton est identique \u00e0 celui d'un r\u00e9ducteur \u00e0 vis sans fin traditionnel. Son pas axial doit \u00eatre \u00e9gal au pas circonf\u00e9rentiel de la roue dent\u00e9e principale. Un r\u00e9ducteur \u00e0 un seul filet avance d'une dent par tour, tandis qu'un r\u00e9ducteur \u00e0 deux filets en avance de deux. Le filetage de la vis sans fin peut \u00eatre \u00e0 gauche ou \u00e0 droite. Le pas de la vis sans fin correspond \u00e0 la distance parcourue par un point de son filetage en un tour. L'angle de pas est l'angle form\u00e9 par la tangente au pas du cylindre et \u00e0 l'axe de la vis sans fin.<br \/>Les r\u00e9ducteurs \u00e0 vis sans fin \u00e0 double filetage sont id\u00e9aux pour les charges importantes. Ils assurent une liaison optimale entre la vis sans fin et la roue dent\u00e9e. Le montage de la vis sans fin exige une grande pr\u00e9cision. La m\u00e9thode de montage par rainure de clavette consiste \u00e0 percer une entaille carr\u00e9e dans l'al\u00e9sage de la roue dent\u00e9e. Ceci emp\u00eache la vis sans fin de tourner sur l'arbre et facilite la transmission du couple. Ensuite, utilisez la vis de blocage pour fixer la roue dent\u00e9e au moyeu.<br \/>Le grand r\u00e9servoir de carburant contribue \u00e0 maintenir la roue \u00e0 vis sans fin propre et r\u00e9duit la chaleur. Il assure \u00e9galement la lubrification, prolongeant ainsi sa dur\u00e9e de vie. Les r\u00e9ducteurs \u00e0 vis sans fin avec r\u00e9servoir d'huile offrent un environnement lubrifi\u00e9 et des surfaces \u00e0 faible frottement. De plus, ils offrent une grande flexibilit\u00e9 d'installation multiposition. Leur carter est usin\u00e9 transversalement pour un alignement pr\u00e9cis. Enfin, des chicanes internes garantissent une ventilation \u00e9tanche.<br \/>Les r\u00e9ducteurs \u00e0 vis sans fin de la s\u00e9rie I260 sont constitu\u00e9s d'un carter monobloc en fonte, d'un arbre de sortie plein ou creux et de roulements \u00e0 rouleaux coniques. Ce r\u00e9ducteur est con\u00e7u pour les applications de faible \u00e0 moyenne puissance. Il offre un excellent rapport qualit\u00e9-prix gr\u00e2ce \u00e0 son faible co\u00fbt initial, son rapport de r\u00e9duction \u00e9lev\u00e9 et son couple important, le tout dans un format compact. De plus, il est plus r\u00e9sistant aux chocs que les autres r\u00e9ducteurs.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_3.webp\" alt=\"r\u00e9ducteur de vers\" width=\"800\" \/>engrenage \u00e0 vis sans fin en laiton<\/h2>\n<p>Le r\u00e9ducteur \u00e0 vis sans fin en laiton est un syst\u00e8me d'engrenage r\u00e9ducteur. Ce type d'engrenage permet une r\u00e9duction importante dans un format compact. Il est \u00e9galement capable de g\u00e9n\u00e9rer un couple \u00e9lev\u00e9. Cependant, il est important de noter que ce r\u00e9ducteur pr\u00e9sente des limitations thermiques qui r\u00e9duisent son rendement. Le choix du lubrifiant pour ce type de r\u00e9ducteur est tr\u00e8s flexible. Toutefois, \u00e9tant donn\u00e9 qu'il s'agit d'un m\u00e9tal jaune, il est essentiel d'utiliser un lubrifiant non r\u00e9actif.<br \/>Les engrenages \u00e0 vis sans fin sont utilis\u00e9s dans de nombreuses applications grand public et industrielles et pr\u00e9sentent des rapports de r\u00e9duction \u00e9lev\u00e9s. Ils sont produits dans diverses configurations et dimensions. Similaires aux engrenages cylindriques \u00e0 denture droite, ils se distinguent par leurs arbres non parall\u00e8les. Les engrenages \u00e0 vis sans fin conviennent \u00e9galement aux applications n\u00e9cessitant une faible vitesse de rotation mais un couple \u00e9lev\u00e9.<br \/>Les engrenages \u00e0 vis sans fin pr\u00e9sentent des avantages distincts par rapport aux autres types d'engrenages. Tout d'abord, contrairement aux engrenages classiques, la vis sans fin tourne selon un mouvement circulaire. Ce m\u00e9canisme emp\u00eache tout mouvement inverse, car l'angle d'h\u00e9lice est faible. De plus, le blocage automatique des vis sans fin contribue \u00e0 emp\u00eacher l'inversion du sens de rotation. Cependant, ce m\u00e9canisme n'est pas totalement fiable. On trouve des engrenages \u00e0 vis sans fin dans les ascenseurs, les moulinets de p\u00eache, les pignons et les syst\u00e8mes de direction assist\u00e9e automobile.<br \/>Un autre avantage des engrenages \u00e0 vis sans fin r\u00e9side dans leur facilit\u00e9 de fabrication. Le principe de leur conception repose sur deux axes perpendiculaires. Deux filets ou plus sont ensuite ajout\u00e9s \u00e0 la vis sans fin. La tangente commune \u00e0 ces deux axes coupe la ligne primitive de l'arbre de la vis sans fin. C'est le principe de la transmission de la vitesse.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"Vente directe d&#039;usine en Chine de r\u00e9ducteurs \u00e0 vis sans fin Mrv50 pour camping-cars, bo\u00eetier en aluminium, petits mod\u00e8les.\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"Vente directe d&#039;usine en Chine de r\u00e9ducteurs \u00e0 vis sans fin Mrv50 pour camping-cars, bo\u00eetier en aluminium, petits mod\u00e8les.\"><br \/>editor by CX 2023-03-27<\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description About Us\u00a0 one.We manufacture and market HB,XB,P, F, S,K,R series speed retarders and transmissions. 2.A range of versions are offered. You are welcome to inquire. 3.We supply certifications:CO\/PVOC\/ FERI\/SUNCAP\/ISO 9001:2008 four.OEM service :logo,lable ,guide ,and packages Product Description \u00a0 FC Parallel Shaft Helical Gearmotor one. FC collection parallel shaft helical gearmotor is primarily [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[799,158,180,159,12,14,166,312,184,182,15,190,191,258,195,20,21,22,316,140,93,150,800,206,423,424,425,464,466,701,468,703,472,215,362,218,221,363,113,365,223],"class_list":["post-1505","post","type-post","status-publish","format-standard","hentry","category-worm-reducers","tag-aluminum-gear","tag-box-gear","tag-box-reducer","tag-china-gear-box","tag-china-gearbox","tag-gear","tag-gear-box","tag-gear-box-gearbox","tag-gear-box-reducer","tag-gear-box-worm","tag-gear-gearbox","tag-gear-reducer","tag-gear-reducer-box","tag-gear-reducer-gearbox","tag-gear-worm","tag-gearbox","tag-gearbox-china","tag-gearbox-gear","tag-gearbox-gear-box","tag-gearbox-reducer","tag-reducer","tag-reducer-gearbox","tag-reducer-shell","tag-reducer-worm-gear","tag-rv-gearbox","tag-rv-reducer","tag-rv-worm-gear-reducer","tag-small-box-gear","tag-small-gear","tag-small-gear-reducer","tag-small-gearbox","tag-small-worm-gear-reducer","tag-small-worm-gearbox","tag-worm-gear","tag-worm-gear-gearbox","tag-worm-gear-reducer","tag-worm-gear-worm","tag-worm-gearbox","tag-worm-reducer","tag-worm-reducer-gearbox","tag-worm-worm-gear"],"_links":{"self":[{"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/posts\/1505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/comments?post=1505"}],"version-history":[{"count":0,"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/posts\/1505\/revisions"}],"wp:attachment":[{"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/media?parent=1505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/categories?post=1505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worm-reducers.xyz\/fr\/wp-json\/wp\/v2\/tags?post=1505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}