{"id":1505,"date":"2023-03-27T08:01:27","date_gmt":"2023-03-27T08:01:27","guid":{"rendered":"http:\/\/worm-reducers.xyz\/china-factory-direct-sales-of-aluminum-shell-small-mrv50-rv-worm-gear-worm-reducer-gear-box-worm-gearbox-china\/"},"modified":"2023-03-27T08:01:27","modified_gmt":"2023-03-27T08:01:27","slug":"china-factory-direct-sales-of-aluminum-shell-small-mrv50-rv-worm-gear-worm-reducer-gear-box-worm-gearbox-china","status":"publish","type":"post","link":"https:\/\/worm-reducers.xyz\/de\/china-factory-direct-sales-of-aluminum-shell-small-mrv50-rv-worm-gear-worm-reducer-gear-box-worm-gearbox-china\/","title":{"rendered":"Direktvertrieb ab Werk China: Kleines MRV50-Schneckengetriebe mit Aluminiumgeh\u00e4use f\u00fcr Wohnmobile (Schneckengetriebe aus China)"},"content":{"rendered":"<p><h2>Produktbeschreibung<\/h2>\n<p>\n<p><h3><b>\u00dcber uns\u00a0<\/b><\/h3>\n<p>1. Wir fertigen und vertreiben Geschwindigkeitsverz\u00f6gerer und Getriebe der Serien HB, XB, P, F, S, K und R. 2. Es wird eine Reihe von Ausf\u00fchrungen angeboten. <b>Sie k\u00f6nnen gerne anfragen.<\/b><\/p>\n<p>3. Wir bieten folgende Zertifizierungen an: CO\/PVOC\/FERI\/SUNCAP\/ISO 9001:2008<\/p>\n<p><p>vier. OEM-Service: Logo, Etikett, Anleitung und Verpackungen<\/p>\n<p>Produktbeschreibung<\/p>\n<p><p>\u00a0<\/p>\n<p><p>FC Parallelwellen-Schr\u00e4gverzahnungsmotor<\/p>\n<p>\n<p><p>Der FC-Reihen-Parallelwellen-Schr\u00e4gverzahnungsmotor basiert haupts\u00e4chlich auf der Bauart der Parallelwellenkonstruktion, bei der eine Mittenl\u00e4nge zwischen Eingangs- und Ausgangswelle vorhanden ist.<br \/>2. Kompaktes Design, gleichm\u00e4\u00dfiger Lauf, h\u00f6here \u00dcbertragungseffizienz, robuste Tragf\u00e4higkeit.<br \/>Drittens. Die Zahnr\u00e4der bestehen aus 20CrMnTi-Legierungsstahl und erreichen durch Anlassen, H\u00e4rten und weitere W\u00e4rmebehandlungen eine H\u00e4rte von HRC 58\u00b0 bis 62\u00b0. Alle Zahnr\u00e4der werden pr\u00e4zise geschliffen, wodurch eine Pr\u00e4zision der G\u00fcteklasse 6 bis 5 erreicht wird.<br \/>vier. Die G\u00fcter wurden vorwiegend in Kr\u00e4nen, F\u00f6rderb\u00e4ndern, Keramikmaschinen usw. verwendet.<br \/>Typ und Spezifikation: FC37~FC157<\/p>\n<p>Artikelparameter<\/p>\n<p>\n<p>\n<p>Organisationsprofil<\/p>\n<p><p>\u00a0<\/p>\n<p>H\u00e4ufig gestellte Fragen<\/p>\n<p><p>\u00a0<\/p>\n<p><b>1. Wie entscheiden wir uns f\u00fcr ein Getriebe, das unseren Bed\u00fcrfnissen entspricht?<\/b><br \/>Sie k\u00f6nnen in unserem Katalog nachsehen, um das passende Getriebe auszuw\u00e4hlen, oder wir unterst\u00fctzen Sie bei der Auswahl, wenn Sie es liefern.<br \/>die technologischen Informationen \u00fcber das erforderliche Ausgangsdrehmoment, die Ausgangsdrehzahl und die Motorparameter usw.<\/p>\n<p><b>zwei. Welche Details sollten wir vor der Platzierung einer Kaufanfrage angeben?<\/b><br \/>a) Getriebeart, \u00dcbersetzungsverh\u00e4ltnis, Eingangs- und Ausgangsart, Eingangsflansch, Montageposition und Motorinformationen usw.<br \/>b) Geh\u00e4usef\u00e4rbung.<br \/>c) Kaufmenge.<br \/>d) Sonstige spezifische Spezifikationen.<\/p>\n<p><b>drei. In welchen Branchen werden Ihre Getriebe eingesetzt?<\/b><br \/>Unsere Getriebe finden breite Anwendung in den Bereichen Textilindustrie, Lebensmittelverarbeitung, Getr\u00e4nkeindustrie und Chemie.<br \/>Rolltreppen, automatisierte Lagersysteme, Metallurgie, Tabakindustrie, Umweltschutz, Logistik und so weiter.<\/p>\n<p><b>vier. Vermarkten Sie Motoren?<\/b><br \/>Wir arbeiten mit zuverl\u00e4ssigen Motorenlieferanten zusammen, die uns seit Langem begleiten. Sie k\u00f6nnen Motoren anbieten.<br \/>mit h\u00f6herer Qualit\u00e4t.<br \/>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anwendung:<\/th>\n<td>Maschinen, Autos, Hebezeuge<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">H\u00e4rte:<\/th>\n<td>Geh\u00e4rtete Zahnoberfl\u00e4che<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installation:<\/th>\n<td>Horizontaler Typ<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Layout:<\/th>\n<td>Erweiterung<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Zahnradform:<\/th>\n<td>Zylinderzahnrad<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Schritt:<\/th>\n<td>Vier-Schritte<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Proben:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 2000\/St\u00fcck<\/strong><br \/>\n                                        <span title=\"1 St\u00fcck (Mindestbestellmenge)\">1 St\u00fcck (Mindestbestellmenge)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Muster anfordern<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anpassung:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Verf\u00fcgbar\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i><br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anwendung:<\/th>\n<td>Maschinen, Autos, Hebezeuge<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">H\u00e4rte:<\/th>\n<td>Geh\u00e4rtete Zahnoberfl\u00e4che<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Installation:<\/th>\n<td>Horizontaler Typ<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Layout:<\/th>\n<td>Erweiterung<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Zahnradform:<\/th>\n<td>Zylinderzahnrad<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Schritt:<\/th>\n<td>Vier-Schritte<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Proben:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 2000\/St\u00fcck<\/strong><br \/>\n                                        <span title=\"1 St\u00fcck (Mindestbestellmenge)\">1 St\u00fcck (Mindestbestellmenge)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Muster anfordern<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Anpassung:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Verf\u00fcgbar\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i><br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Was ist ein Schneckengetriebe?<\/h2>\n<p>Das Schneckengetriebe dient zur \u00c4nderung der Abtriebsdrehzahl einer mechanischen Anlage. Es besteht aus Schnecken- und Schr\u00e4gverzahnungen, die auf der Eingangsseite der Anlage montiert sind. In manchen F\u00e4llen kann dieses Untersetzungssystem mehrstufig ausgef\u00fchrt sein, wodurch extrem niedrige Abtriebsdrehzahlen m\u00f6glich werden. Es zeichnet sich durch geringen Energieverbrauch und geringe Vibrationen aus.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/T_worm_reducer_3.webp\" alt=\"Wurmreduzierer\" width=\"800\" \/>Hohlwellen-Schneckengetriebe<\/h2>\n<p>Das Schneckengetriebe ist ein effektives Ger\u00e4t zur Drehzahlreduzierung von Maschinen. Die Verwendung von Hartstahl oder Nichteisenmetallen f\u00fcr die Schnecke erh\u00f6ht den Wirkungsgrad. Schnecken aus Hartstahl erzeugen mehr W\u00e4rme als solche aus Baustahl. Unterschiedliche W\u00e4rmeausdehnung f\u00fchrt zu Spaltma\u00dfen zwischen den Passfl\u00e4chen. Trotz seiner vielen Vorteile neigen Schneckengetriebe zu \u00d6lleckagen, was aus verschiedenen Gr\u00fcnden problematisch sein kann.<br \/>Hohlwellen-Schneckengetriebe sind in verschiedenen \u00dcbersetzungsverh\u00e4ltnissen erh\u00e4ltlich und mit vielen Motortypen kompatibel. Sie sind als Ein- und Zweiachsengetriebe verf\u00fcgbar und k\u00f6nnen horizontal oder vertikal montiert werden. Dar\u00fcber hinaus sind sie mit Zwischen\u00fcbersetzungen sowie als Vier- und F\u00fcnfganggetriebe erh\u00e4ltlich. Zus\u00e4tzliche Abtriebswellen k\u00f6nnen ebenfalls angeschlossen werden.<br \/>Eine weitere Bauart von Schneckengetrieben ist das mehrstufige Getriebe. Dieses Getriebe verf\u00fcgt \u00fcber mehrere Stufen und erm\u00f6glicht so extrem niedrige Ausgangsdrehzahlen. Neben dem hohen \u00dcbersetzungsverh\u00e4ltnis zeichnet sich das mehrstufige Getriebe durch geringe Ger\u00e4uschentwicklung, geringe Vibrationen und einen niedrigen Energieverbrauch aus.<br \/>Schneckengetriebe bieten platzsparende L\u00f6sungen und ein h\u00f6heres Drehmoment. Agknx Gearbox bietet Schneckengetriebe an, die g\u00e4ngige Probleme bei der Untersetzung l\u00f6sen. Das Unternehmen hat sein Produktsortiment zudem auf den Badezimmermarkt ausgeweitet. Im Vergleich zu Standardgetrieben zeichnen sich Schneckengetriebe durch einen niedrigeren Preis und ein h\u00f6heres Drehmoment aus.<br \/>Agknx Schneckengetriebe<\/h2>\n<p>Das Schneckengetriebe vom Typ Agknx verf\u00fcgt \u00fcber Linienkontakt und findet breite Anwendung in Schwermaschinen. Diese Getriebe zeichnen sich durch eine hohe Belastbarkeit aus, reagieren jedoch empfindlich auf Fluchtungs- und Fertigungsfehler. Durch den Einsatz von Punktkontakt l\u00e4sst sich die Zuverl\u00e4ssigkeit dieser Getriebe erh\u00f6hen und ihre Belastbarkeit verbessern.<br \/>Ein weiterer wesentlicher Vorteil des Agknx-Schneckengetriebes ist seine hohe Belastbarkeit. Das Zahnprofil der Zahnr\u00e4der weist ein hohes relatives Schlupfverh\u00e4ltnis auf, was die Effizienz und die Belastbarkeit verbessert. Dar\u00fcber hinaus sorgt der gro\u00dfe Winkel zwischen Gleitrichtung und Kontaktlinie f\u00fcr einen niedrigen Reibungskoeffizienten. Das Agknx-Schneckengetriebe zeichnet sich au\u00dferdem durch hochwertiges, einsatzgeh\u00e4rtetes Stahl- und Phosphorbronze-Guss aus, was ihm eine au\u00dfergew\u00f6hnliche Langlebigkeit verleiht. Zus\u00e4tzlich ist das Zahnprofil sehr pr\u00e4zise, \u200b\u200bder Lauf leise und die Drehzahlschwankungen sind gering.<br \/>Die Schneckengetriebe von Agknx sind f\u00fcr einen Dauerbetrieb von bis zu zehn Stunden t\u00e4glich unter gleichm\u00e4\u00dfiger Last ausgelegt. Die Konstruktion dieses Schneckengetriebes basiert auf der langj\u00e4hrigen Erfahrung von Sumitomo Heavy Industries im Bereich der Getriebetechnik. Die glatte Oberfl\u00e4chenstruktur und das pr\u00e4zise Zahnprofil der Zahnr\u00e4der gew\u00e4hrleisten, dass diese hohen Belastungen standhalten, ohne den Schmierfilm zu besch\u00e4digen. Dar\u00fcber hinaus sind die Schneckenwellen von Agknx speziell auf die optimale Steifigkeit ausgelegt.<br \/>Die Schneckengetriebe von Agknx sind so konstruiert, dass sie die Belastbarkeit maximieren und gleichzeitig den Energieverbrauch minimieren. Die vollst\u00e4ndig ineinandergreifenden Z\u00e4hne reduzieren den Fl\u00e4chendruck auf die Schneckenradz\u00e4hne und erh\u00f6hen so die Belastbarkeit.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/C_worm_reducer_3.webp\" alt=\"Wurmreduzierer\" width=\"800\" \/>Doppelkehl-Schneckengetriebe<\/h2>\n<p>Bei der Auswahl eines Schneckengetriebes mit zwei Zahnh\u00e4lsen sind einige Punkte zu beachten. Zun\u00e4chst muss der Durchmesser des Fu\u00dfkreises der Teilung des gr\u00f6\u00dferen Zahnrads entsprechen. Dies wird \u00fcblicherweise durch Messen des Abstands zwischen benachbarten Z\u00e4hnen ermittelt. Alternativ kann der Modul der Schnecke verwendet werden. Dieser Wert wird im Dialogfeld \u201eModul der Schnecke\u201c eingegeben. Dar\u00fcber hinaus sollte die axiale Steigung der Schnecke dem Teilkreisdurchmesser entsprechen.<br \/>Doppelschneckengetriebe sind eine ausgezeichnete Wahl f\u00fcr anspruchsvolle Anwendungen. Ihre Konstruktion ist ideal f\u00fcr hohe Belastungen, da sie eine engere Verbindung zwischen Schnecke und Zahnrad gew\u00e4hrleistet. Sie sind zudem kompakter als andere Getriebearten und vergleichbar mit einer Feingewindespindel.<br \/>Der Wirkungsgrad eines Schneckengetriebes mit doppeltem Eingriff h\u00e4ngt vom Material der Zahnr\u00e4der und der Schnecke ab. Typischerweise bestehen die Zahnr\u00e4der aus einsatzgeh\u00e4rtetem Stahl, w\u00e4hrend die Schneckengetriebe aus Bronze oder Gusseisen gefertigt sind. In manchen F\u00e4llen kann eine Kombination aus Gusseisen und Bronze verwendet werden.<br \/>Die Durchbiegung der Schneckenwelle wird auch von den Zahnparametern beeinflusst. Zahnh\u00f6he, Eingriffswinkel und Abmessungen wirken sich auf die Durchbiegung der Schneckenwelle aus. Dar\u00fcber hinaus ist die Anzahl der Schneckengewinde ein weiterer wichtiger Parameter, der die Durchbiegung der Schneckenwelle beeinflusst.<br \/>Doppelschneckengetriebe werden h\u00e4ufig in industriellen Anwendungen eingesetzt, in denen eine hohe Getriebeuntersetzung erforderlich ist. Die Schnecke besitzt eine konkave Innenverzahnung, die sich zur Erzielung verschiedener \u00dcbersetzungsverh\u00e4ltnisse anpassen l\u00e4sst. Schneckengetriebe und Schneckengetriebebaugruppen m\u00fcssen fachgerecht auf ihren Wellen montiert werden, um einen R\u00fccklauf zu verhindern.<br \/>Schneckengetriebe aus Messing<\/h2>\n<p>Das grundlegende Funktionsprinzip des Messing-Schneckengetriebes entspricht dem des herk\u00f6mmlichen Schneckengetriebes. Seine axiale Teilung muss der Umfangsteilung des gr\u00f6\u00dferen Zahnrads entsprechen. Bei eing\u00e4ngigen Schneckengetrieben wird pro Umdrehung ein Zahn weitergeschaltet, bei zweig\u00e4ngigen zwei. Das Schneckengewinde ist entweder links- oder rechtsg\u00e4ngig. Die Steigung einer Schnecke ist die Strecke, die ein Punkt auf dem Schneckengewinde bei einer Umdrehung zur\u00fccklegt. Der Steigungswinkel ist der Winkel zwischen der Steigung des Zylinders und der Schneckenachse.<br \/>Doppelgewinde-Schneckengetriebe eignen sich optimal f\u00fcr hohe Belastungen. Sie gew\u00e4hrleisten eine besonders feste Verbindung zwischen Schnecke und Schneckenrad. Die Montage des Schneckenrades erfordert pr\u00e4zises Arbeiten. Bei der Keilwellenmontage wird eine rechtwinklige Nut in die Zahnradbohrung gebohrt. Dies verhindert das Verdrehen der Schnecke auf der Welle und optimiert die Drehmoment\u00fcbertragung. Anschlie\u00dfend wird das Zahnrad mithilfe der Stellschraube an der Nabe befestigt.<br \/>Der gro\u00dfe Kraftstofftank tr\u00e4gt zur Sauberkeit des Schneckengetriebes bei und reduziert die W\u00e4rmeentwicklung. Er sorgt au\u00dferdem f\u00fcr Schmierung und damit f\u00fcr eine l\u00e4ngere Lebensdauer. Schneckengetriebe mit \u00d6lbeh\u00e4ltern gew\u00e4hrleisten eine optimale Schmierung und reibungsarme Oberfl\u00e4chen. Dar\u00fcber hinaus bietet das Getriebe Flexibilit\u00e4t bei der Montage in verschiedenen Positionen. Das Geh\u00e4use ist f\u00fcr pr\u00e4zise Ausrichtung quergefr\u00e4st und verf\u00fcgt \u00fcber interne Leitbleche f\u00fcr eine leckagefreie Bel\u00fcftung.<br \/>Die Schneckengetriebe der Serie I260 bestehen aus einteiligen Eisengeh\u00e4usen mit massiven oder hohlen Abtriebswellen und Kegelrollenlagern. Dieses Getriebe ist f\u00fcr Anwendungen mit niedriger bis mittlerer Leistung ausgelegt. Es bietet ein gutes Preis-Leistungs-Verh\u00e4ltnis durch geringe Anschaffungskosten, ein hohes \u00dcbersetzungsverh\u00e4ltnis und ein hohes Drehmoment in kompakter Bauweise. Zudem ist es sto\u00dffester als andere Getriebe.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/B_worm_reducer_3.webp\" alt=\"Wurmreduzierer\" width=\"800\" \/>Schneckengetriebe aus Messing<\/h2>\n<p>Ein Schneckengetriebe aus Messing ist ein Untersetzungsgetriebe. Diese Getriebeart erm\u00f6glicht eine hohe Untersetzung auf kleinem Raum. Es ist au\u00dferdem in der Lage, ein hohes Drehmoment zu erzeugen. Allerdings ist zu beachten, dass dieses Getriebe thermischen Beschr\u00e4nkungen unterliegt, die seinen Wirkungsgrad mindern. Die Wahl des Schmierstoffs ist sehr flexibel. Da Messing jedoch ein Buntmetall ist, muss der Schmierstoff reaktionsarm sein.<br \/>Schneckengetriebe finden in vielen Konsumg\u00fcter- und Industrieanwendungen Verwendung und zeichnen sich durch hohe Untersetzungsverh\u00e4ltnisse aus. Sie werden in verschiedenen Ausf\u00fchrungen und Gr\u00f6\u00dfen gefertigt. Schneckengetriebe \u00e4hneln Stirnr\u00e4dern, besitzen jedoch nicht parallele Wellen. Sie eignen sich besonders f\u00fcr Anwendungen, die eine niedrige Ausgangsdrehzahl bei gleichzeitig hohem Drehmoment erfordern.<br \/>Schneckengetriebe bieten gegen\u00fcber anderen Getrieben einige entscheidende Vorteile. Im Gegensatz zu Standardzahnr\u00e4dern dreht sich die Schnecke in einer wurmartigen Bewegung. Dieser Mechanismus verhindert eine R\u00fcckw\u00e4rtsbewegung, da der Steigungswinkel des Schneckengetriebes klein ist. Zus\u00e4tzlich blockieren die Schnecken selbst, was ebenfalls ein Zur\u00fcckdrehen verhindert. Allerdings ist dieser Mechanismus nicht v\u00f6llig zuverl\u00e4ssig. Schneckengetriebe finden Anwendung in Aufz\u00fcgen, Angelrollen, Kettenr\u00e4dern und Servolenkungen von Kraftfahrzeugen.<br \/>Ein weiterer Vorteil von Schneckengetrieben ist ihre einfache Fertigung. Das Prinzip dieser Konstruktion beruht auf zwei zueinander senkrechten Achsen. Anschlie\u00dfend werden dem Schneckenrad zwei oder mehr Gewindeg\u00e4nge hinzugef\u00fcgt. Die gemeinsame Tangente dieser beiden Achsen schneidet die Teilkreislinie der Schneckenwelle. Dies ist die Grundlage f\u00fcr die \u00dcbertragungsgeschwindigkeit.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l1.webp\" alt=\"Direktvertrieb ab Werk China: Kleines MRV50-Schneckengetriebe mit Aluminiumgeh\u00e4use f\u00fcr Wohnmobile (Schneckengetriebe aus China)\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/worm_reducer\/Worm_Reducer_l2.webp\" alt=\"Direktvertrieb ab Werk China: Kleines MRV50-Schneckengetriebe mit Aluminiumgeh\u00e4use f\u00fcr Wohnmobile (Schneckengetriebe aus China)\"><br \/>Bearbeitet von CX am 27.03.2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description About Us\u00a0 one.We manufacture and market HB,XB,P, F, S,K,R series speed retarders and transmissions. 2.A range of versions are offered. You are welcome to inquire. 3.We supply certifications:CO\/PVOC\/ FERI\/SUNCAP\/ISO 9001:2008 four.OEM service :logo,lable ,guide ,and packages Product Description \u00a0 FC Parallel Shaft Helical Gearmotor one. FC collection parallel shaft helical gearmotor is primarily [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[799,158,180,159,12,14,166,312,184,182,15,190,191,258,195,20,21,22,316,140,93,150,800,206,423,424,425,464,466,701,468,703,472,215,362,218,221,363,113,365,223],"class_list":["post-1505","post","type-post","status-publish","format-standard","hentry","category-worm-reducers","tag-aluminum-gear","tag-box-gear","tag-box-reducer","tag-china-gear-box","tag-china-gearbox","tag-gear","tag-gear-box","tag-gear-box-gearbox","tag-gear-box-reducer","tag-gear-box-worm","tag-gear-gearbox","tag-gear-reducer","tag-gear-reducer-box","tag-gear-reducer-gearbox","tag-gear-worm","tag-gearbox","tag-gearbox-china","tag-gearbox-gear","tag-gearbox-gear-box","tag-gearbox-reducer","tag-reducer","tag-reducer-gearbox","tag-reducer-shell","tag-reducer-worm-gear","tag-rv-gearbox","tag-rv-reducer","tag-rv-worm-gear-reducer","tag-small-box-gear","tag-small-gear","tag-small-gear-reducer","tag-small-gearbox","tag-small-worm-gear-reducer","tag-small-worm-gearbox","tag-worm-gear","tag-worm-gear-gearbox","tag-worm-gear-reducer","tag-worm-gear-worm","tag-worm-gearbox","tag-worm-reducer","tag-worm-reducer-gearbox","tag-worm-worm-gear"],"_links":{"self":[{"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/posts\/1505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/comments?post=1505"}],"version-history":[{"count":0,"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/posts\/1505\/revisions"}],"wp:attachment":[{"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/media?parent=1505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/categories?post=1505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worm-reducers.xyz\/de\/wp-json\/wp\/v2\/tags?post=1505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}